{"id":60,"date":"2018-09-24T09:08:01","date_gmt":"2018-09-24T09:08:01","guid":{"rendered":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg"},"modified":"2018-09-24T09:08:01","modified_gmt":"2018-09-24T09:08:01","slug":"kios-pintar-touchscreen-sistem-digital","status":"inherit","type":"attachment","link":"https:\/\/kipin.id\/web\/kipinkios-pintar-untuk-pendidikan-indonesia\/kios-pintar-touchscreen-sistem-digital\/","title":{"rendered":"kios-pintar-touchscreen-sistem-digital"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg'><img width=\"200\" height=\"300\" src=\"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-200x300.jpg 200w, https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg 455w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":455,"height":683,"file":"2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg","sizes":{"thumbnail":{"file":"kios-pintar-touchscreen-sistem-digital-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-150x150.jpg"},"medium":{"file":"kios-pintar-touchscreen-sistem-digital-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-200x300.jpg"},"zerif-post-thumbnail":{"file":"kios-pintar-touchscreen-sistem-digital-250x250.jpg","width":250,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-250x250.jpg"},"zerif-post-thumbnail-large":{"file":"kios-pintar-touchscreen-sistem-digital-455x500.jpg","width":455,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-455x500.jpg"},"zerif-post-thumbnail-large-table":{"file":"kios-pintar-touchscreen-sistem-digital-455x300.jpg","width":455,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-455x300.jpg"},"zerif-post-thumbnail-large-mobile":{"file":"kios-pintar-touchscreen-sistem-digital-400x200.jpg","width":400,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-400x200.jpg"},"zerif_project_photo":{"file":"kios-pintar-touchscreen-sistem-digital-285x214.jpg","width":285,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-285x214.jpg"},"zerif_our_team_photo":{"file":"kios-pintar-touchscreen-sistem-digital-174x174.jpg","width":174,"height":174,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital-174x174.jpg"},"full":{"file":"kios-pintar-touchscreen-sistem-digital.jpg","width":455,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon EOS 80D","caption":"","created_timestamp":"1489758983","copyright":"","focal_length":"135","iso":"100","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":59,"source_url":"https:\/\/kipin.id\/web\/wp-content\/uploads\/2018\/09\/kios-pintar-touchscreen-sistem-digital.jpg","_links":{"self":[{"href":"https:\/\/kipin.id\/web\/wp-json\/wp\/v2\/media\/60"}],"collection":[{"href":"https:\/\/kipin.id\/web\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/kipin.id\/web\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/kipin.id\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kipin.id\/web\/wp-json\/wp\/v2\/comments?post=60"}]}}